{"id":876,"date":"2019-08-28T00:00:00","date_gmt":"2019-08-27T22:00:00","guid":{"rendered":"https:\/\/101.dfja.eu\/10-bistro-babylone\/"},"modified":"2019-10-01T16:48:56","modified_gmt":"2019-10-01T14:48:56","slug":"10-bistro-babylone","status":"publish","type":"post","link":"https:\/\/101.dfja.eu\/fr\/10-bistro-babylone\/","title":{"rendered":"10 | Bistro Babylone"},"content":{"rendered":"<p>Les personnes int\u00e9ress\u00e9es par les langues se retrouvent dans une atmosph\u00e8re d\u00e9tendue dans un caf\u00e9 ou un restaurant. Un fanion indique quelle langue est parl\u00e9e \u00e0 quelle table. Une personne prend en charge la mod\u00e9ration. Un sujet de conversation peut \u00eatre convenu \u00e0 l\u2018avance, mais ne doit pas n\u00e9cessairement l\u2018\u00eatre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les personnes int\u00e9ress\u00e9es par les langues se retrouvent dans une atmosph\u00e8re d\u00e9tendue dans un caf\u00e9 ou un restaurant. Un fanion indique quelle langue est parl\u00e9e \u00e0 quelle table. Une personne prend en charge la mod\u00e9ration. Un sujet de conversation peut \u00eatre convenu \u00e0 l\u2018avance, mais ne doit pas n\u00e9cessairement l\u2018\u00eatre.<\/p>\n","protected":false},"author":1,"featured_media":1383,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[13,5],"tags":[],"class_list":["post-876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-non-classifiee"],"acf":[],"_links":{"self":[{"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/posts\/876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/comments?post=876"}],"version-history":[{"count":1,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/posts\/876\/revisions"}],"predecessor-version":[{"id":1000,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/posts\/876\/revisions\/1000"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/media\/1383"}],"wp:attachment":[{"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/media?parent=876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/categories?post=876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/tags?post=876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}