{"id":880,"date":"2019-08-24T00:00:00","date_gmt":"2019-08-23T22:00:00","guid":{"rendered":"https:\/\/101.dfja.eu\/14-preparons-noel\/"},"modified":"2020-06-20T16:08:37","modified_gmt":"2020-06-20T14:08:37","slug":"14-preparons-noel","status":"publish","type":"post","link":"https:\/\/101.dfja.eu\/fr\/14-preparons-noel\/","title":{"rendered":"14 | Pr\u00e9parons No\u00ebl"},"content":{"rendered":"<p>Pour \u00e9viter les semaines stressantes, on se rencontre d\u00e9j\u00e0 pendant la derni\u00e8re semaine de novembre ou la premi\u00e8re semaine de d\u00e9cembre pour d\u00e9couvrir les rites habituels de No\u00ebl : faire les couronnes de l\u2018Avent ou la b\u00fbche de No\u00ebl, boire du vin chaud, cuisiner, bricoler et aller sur les march\u00e9s de No\u00ebl.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour \u00e9viter les semaines stressantes, on se rencontre d\u00e9j\u00e0 pendant la derni\u00e8re semaine de novembre ou la premi\u00e8re semaine de d\u00e9cembre pour d\u00e9couvrir les rites habituels de No\u00ebl : faire les couronnes de l\u2018Avent ou la b\u00fbche de No\u00ebl, boire du vin chaud, cuisiner, bricoler et aller sur les march\u00e9s de No\u00ebl.<\/p>\n","protected":false},"author":1,"featured_media":1388,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"acf":[],"_links":{"self":[{"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/posts\/880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/comments?post=880"}],"version-history":[{"count":1,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/posts\/880\/revisions"}],"predecessor-version":[{"id":1004,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/posts\/880\/revisions\/1004"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/media\/1388"}],"wp:attachment":[{"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/media?parent=880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/categories?post=880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/tags?post=880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}