{"id":883,"date":"2019-08-21T00:00:00","date_gmt":"2019-08-20T22:00:00","guid":{"rendered":"https:\/\/101.dfja.eu\/17-je-taime-mon-amour\/"},"modified":"2020-06-20T16:09:25","modified_gmt":"2020-06-20T14:09:25","slug":"17-je-taime-mon-amour","status":"publish","type":"post","link":"https:\/\/101.dfja.eu\/fr\/17-je-taime-mon-amour\/","title":{"rendered":"17 | Je t&rsquo;aime, mon amour"},"content":{"rendered":"<p>En petits groupes, les jeunes produisent des romans photos bilingues qui jouent dans les villes partenaires. Du drame Rom\u00e9o &amp; Juliette au vol d\u2018art dans un mus\u00e9e en passant par le Petit Prince dans la Banlieue, tout est permis !<br \/>\nL\u2018appli Book Creator, par exemple, fournit une assistance pour la conception !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En petits groupes, les jeunes produisent des romans photos bilingues qui jouent dans les villes partenaires. Du drame Rom\u00e9o &amp; Juliette au vol d\u2018art dans un mus\u00e9e en passant par le Petit Prince dans la Banlieue, tout est permis ! L\u2018appli Book Creator, par exemple, fournit une assistance pour la conception !<\/p>\n","protected":false},"author":1,"featured_media":1392,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-883","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"acf":[],"_links":{"self":[{"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/posts\/883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/comments?post=883"}],"version-history":[{"count":2,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/posts\/883\/revisions"}],"predecessor-version":[{"id":1489,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/posts\/883\/revisions\/1489"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/media\/1392"}],"wp:attachment":[{"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/media?parent=883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/categories?post=883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/tags?post=883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}