{"id":915,"date":"2019-07-20T00:00:00","date_gmt":"2019-07-19T22:00:00","guid":{"rendered":"https:\/\/101.dfja.eu\/49-sports-conviviaux\/"},"modified":"2019-11-16T17:15:27","modified_gmt":"2019-11-16T16:15:27","slug":"49-sports-conviviaux","status":"publish","type":"post","link":"https:\/\/101.dfja.eu\/fr\/49-sports-conviviaux\/","title":{"rendered":"49 | Sports conviviaux"},"content":{"rendered":"<p>Boules, p\u00e9tanque, quilles : m\u00eame les d\u00e9butant.e.s peuvent s\u2018y mettre et y prendre plaisir. La p\u00e9tanque est tr\u00e8s populaire en France, le jeu de quilles l\u2018est davantage en Allemagne.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Boules, p\u00e9tanque, quilles : m\u00eame les d\u00e9butant.e.s peuvent s\u2018y mettre et y prendre plaisir. La p\u00e9tanque est tr\u00e8s populaire en France, le jeu de quilles l\u2018est davantage en Allemagne.<\/p>\n","protected":false},"author":1,"featured_media":1076,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-915","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"acf":[],"_links":{"self":[{"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/posts\/915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/comments?post=915"}],"version-history":[{"count":2,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/posts\/915\/revisions"}],"predecessor-version":[{"id":1260,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/posts\/915\/revisions\/1260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/media\/1076"}],"wp:attachment":[{"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/media?parent=915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/categories?post=915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/tags?post=915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}