{"id":947,"date":"2019-06-18T00:00:00","date_gmt":"2019-06-17T22:00:00","guid":{"rendered":"https:\/\/101.dfja.eu\/81-cadeaux-durables\/"},"modified":"2019-11-16T17:24:34","modified_gmt":"2019-11-16T16:24:34","slug":"81-cadeaux-durables","status":"publish","type":"post","link":"https:\/\/101.dfja.eu\/fr\/81-cadeaux-durables\/","title":{"rendered":"81 | Cadeaux durables"},"content":{"rendered":"<p>Lors d\u2018une visite des invit\u00e9s de la ville jumel\u00e9e, un arbre est plant\u00e9 &#8211; un grand monument qui grandit avec l&rsquo;amiti\u00e9 ! Un carr\u00e9 dans un jardin communautaire ou sur une place publique est \u00e9galement envisageable. La conception et construction d\u2018un banc du jumelage, peut-\u00eatre m\u00eame avec la silhouette ou des monuments de la ville partenaire, sont possibles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lors d\u2018une visite des invit\u00e9s de la ville jumel\u00e9e, un arbre est plant\u00e9 &#8211; un grand monument qui grandit avec l&rsquo;amiti\u00e9 ! Un carr\u00e9 dans un jardin communautaire ou sur une place publique est \u00e9galement envisageable. La conception et construction d\u2018un banc du jumelage, peut-\u00eatre m\u00eame avec la silhouette ou des monuments de la ville partenaire, sont possibles.<\/p>\n","protected":false},"author":1,"featured_media":1071,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-947","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"acf":[],"_links":{"self":[{"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/posts\/947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/comments?post=947"}],"version-history":[{"count":2,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/posts\/947\/revisions"}],"predecessor-version":[{"id":1271,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/posts\/947\/revisions\/1271"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/media\/1071"}],"wp:attachment":[{"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/media?parent=947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/categories?post=947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/101.dfja.eu\/fr\/wp-json\/wp\/v2\/tags?post=947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}